{"id":7960,"date":"2018-06-25T22:15:14","date_gmt":"2018-06-25T22:15:14","guid":{"rendered":"http:\/\/www.comunidadcalatayud.com\/?p=7960"},"modified":"2018-06-25T22:15:14","modified_gmt":"2018-06-25T22:15:14","slug":"primer-encuentro-sobre-la-despoblacion-en-la-comarca-de-calatayud","status":"publish","type":"post","link":"https:\/\/www.comunidadcalatayud.com\/index.php\/2018\/06\/25\/primer-encuentro-sobre-la-despoblacion-en-la-comarca-de-calatayud\/","title":{"rendered":"Primer Encuentro sobre la despoblaci\u00f3n en la Comarca de Calatayud"},"content":{"rendered":"<p>El Primer Encuentro sobre la despoblaci\u00f3n en la Comarca de Calatayud genera un minucioso an\u00e1lisis de la despoblaci\u00f3n en nuestro territorio<\/p>\n<p>Ayer, mi\u00e9rcoles, se celebr\u00f3 el Primer Encuentro sobre la Despoblaci\u00f3n, en el que se puso encima de la mesa el problema de la despoblaci\u00f3n y se estudiaron algunas estrategias dinamizadoras en el entorno rural.<\/p>\n<p>La apertura del encuentro, en el que participaron m\u00e1s de 30 personas, corri\u00f3 a cargo de Ram\u00f3n Duce, Presidente de la Comarca Comunid<span class=\"text_exposed_show\">ad de Calatayud, y al que asistieron tambi\u00e9n los presidentes de las comarcas de el Aranda y de Campo de Daroca, la totalidad de agentes de empleo y desarrollo local (AEDL) dependientes de la oficina del Inaem de Calatayud, as\u00ed como su director, y el gerente y t\u00e9cnico de ADRI Calatayud-Aranda.<\/span><\/p>\n<div class=\"text_exposed_show\">\n<p>Como ponentes participaron Luis Antonio Saez, Director de la C\u00e1tedra sobre la despoblaci\u00f3n de la Universidad de Zaragoza, Placido Diez, Coordinador de Cuarto Espacio de la DPZ, Maite Gonz\u00e1lez, Gerente de ADEFO Cinco Villas, Luc\u00eda Cam\u00f3n, de Pueblos en arte, y Javier Allu\u00e9, Comisario para la lucha contra la Despoblaci\u00f3n del Gobierno de Arag\u00f3n.<\/p>\n<p>La ponencia de Luis S\u00e1ez (director de la c\u00e1tedra), bajo el t\u00edtulo \u00abEstrategias dinamizadoras del entorno Rural\u00bb, analiz\u00f3 la problem\u00e1tica del entorno rural, con un an\u00e1lisis minucioso tanto de la situaci\u00f3n como las posibles causas del \u00e9xodo rural.<\/p>\n<p>Placido Diez hizo un balance del trabajo realizado desde Cuarto Espacio de la DPZ, dejando la importancia de trabajar conjuntamente, con el apoyo de programas como el de \u00abAyudas a la despoblaci\u00f3n\u00bb y el de \u00abDesaf\u00edo de pr\u00e1cticas para j\u00f3venes en el entorno rural\u00bb.<\/p>\n<p>En cuanto a la ponencia de Maite Gonz\u00e1lez, trat\u00f3 sobre el trabajo llevado a cabo por ADEFO, y otros en los que participa, directamente relacionados con la despoblaci\u00f3n, como \u00abAbraza la Tierra\u00bb, \u00abPueblos vivos\u00bb o \u00abJ\u00f3venes dinamizadores rurales\u00bb<\/p>\n<p>Luc\u00eda Cam\u00f3n, habl\u00f3 de proyectos como \u00abPueblos en Arte\u00bb, \u00abSaltamontes\u00bb, \u00abProyecto 234\u00bb y el cortometraje \u00abSo\u00f1ando un lugar\u00bb, entre otros proyectos que est\u00e1n desarrollando en nuestro territorio.<\/p>\n<p>Javier Allu\u00e9 prest\u00f3 todo su apoyo a los comparecientes e insisti\u00f3 en la importancia de mantener reuniones como la que se estaba llevado a cabo. Allu\u00e9 explic\u00f3 el esfuerzo que se est\u00e1 haciendo desde su posici\u00f3n de Comisario para insertar la problem\u00e1tica de la despoblaci\u00f3n en todas las \u00e1reas posibles de la Administraci\u00f3n.<\/p>\n<p>Las ponencias terminaron con un interesante debate final en el que tomaron la palabra alcaldes y concejales de la Comarca, as\u00ed como otros t\u00e9cnicos de entre los asistentes.<\/p>\n<\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7961 aligncenter\" src=\"http:\/\/www.comunidadcalatayud.com\/wp-content\/uploads\/2018\/06\/35852477_2067255296855821_8222355648537427968_n-300x225.jpg\" alt=\"\" width=\"403\" height=\"272\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"excerpt\">El Primer Encuentro sobre la despoblaci\u00f3n en la Comarca de Calatayud genera un minucioso an\u00e1lisis de la despoblaci\u00f3n en nuestro territorio Ayer, mi\u00e9rcoles, se celebr\u00f3 el Primer Encuentro sobre la Despoblaci\u00f3n, en el que se puso encima de la mesa el problema de la despoblaci\u00f3n y se estudiaron algunas estrategias dinamizadoras en el entorno rural. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7962,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[],"class_list":["post-7960","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.comunidadcalatayud.com\/index.php\/wp-json\/wp\/v2\/posts\/7960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comunidadcalatayud.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comunidadcalatayud.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comunidadcalatayud.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comunidadcalatayud.com\/index.php\/wp-json\/wp\/v2\/comments?post=7960"}],"version-history":[{"count":2,"href":"https:\/\/www.comunidadcalatayud.com\/index.php\/wp-json\/wp\/v2\/posts\/7960\/revisions"}],"predecessor-version":[{"id":7964,"href":"https:\/\/www.comunidadcalatayud.com\/index.php\/wp-json\/wp\/v2\/posts\/7960\/revisions\/7964"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comunidadcalatayud.com\/index.php\/wp-json\/wp\/v2\/media\/7962"}],"wp:attachment":[{"href":"https:\/\/www.comunidadcalatayud.com\/index.php\/wp-json\/wp\/v2\/media?parent=7960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comunidadcalatayud.com\/index.php\/wp-json\/wp\/v2\/categories?post=7960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comunidadcalatayud.com\/index.php\/wp-json\/wp\/v2\/tags?post=7960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}